{"id":6,"count":0,"description":"","link":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/","name":"life coach","slug":"life-coach","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>life coach Archive | Daniela Amberg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"life coach Archive | Daniela Amberg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/\" \/>\n<meta property=\"og:site_name\" content=\"Daniela Amberg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/tag\\\/life-coach\\\/\",\"url\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/tag\\\/life-coach\\\/\",\"name\":\"life coach Archive | Daniela Amberg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/tag\\\/life-coach\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/tag\\\/life-coach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"life coach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/\",\"name\":\"Daniela Amberg\",\"description\":\"Life coach\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/danielaamberg.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"life coach Archive | Daniela Amberg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/","og_locale":"en_GB","og_type":"article","og_title":"life coach Archive | Daniela Amberg","og_url":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/","og_site_name":"Daniela Amberg","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/","url":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/","name":"life coach Archive | Daniela Amberg","isPartOf":{"@id":"https:\/\/danielaamberg.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/danielaamberg.de\/en\/tag\/life-coach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/danielaamberg.de\/en\/"},{"@type":"ListItem","position":2,"name":"life coach"}]},{"@type":"WebSite","@id":"https:\/\/danielaamberg.de\/en\/#website","url":"https:\/\/danielaamberg.de\/en\/","name":"Daniela Amberg","description":"Life coach","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/danielaamberg.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/danielaamberg.de\/en\/wp-json\/wp\/v2\/tags\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danielaamberg.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/danielaamberg.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/danielaamberg.de\/en\/wp-json\/wp\/v2\/posts?tags=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}